{"id":84,"count":59,"description":"subcategoria manijas eleva vehiculos livianos","link":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/manijas-elevavidrios\/","name":"Manijas Elevavidrios","slug":"manijas-elevavidrios","taxonomy":"product_cat","parent":16,"meta":[],"menu_order":0,"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"subcategoria manijas eleva vehiculos livianos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/manijas-elevavidrios\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/84\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cruzcartrade.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/shop\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/product-category\\\/vehiculos-livianos\\\/#listItem\",\"name\":\"Veh\\u00edculos livianos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/product-category\\\/vehiculos-livianos\\\/#listItem\",\"position\":3,\"name\":\"Veh\\u00edculos livianos\",\"item\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/product-category\\\/vehiculos-livianos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/product-category\\\/vehiculos-livianos\\\/manijas-elevavidrios\\\/#listItem\",\"name\":\"Manijas Elevavidrios\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/shop\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/product-category\\\/vehiculos-livianos\\\/manijas-elevavidrios\\\/#listItem\",\"position\":4,\"name\":\"Manijas Elevavidrios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/product-category\\\/vehiculos-livianos\\\/#listItem\",\"name\":\"Veh\\u00edculos livianos\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/84\\\/#collectionpage\",\"url\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/84\\\/\",\"name\":\"Manijas Elevavidrios - cruzcartrade.com\",\"description\":\"subcategoria manijas eleva vehiculos livianos\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/84\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/#organization\",\"name\":\"cruzcartrade.com\",\"description\":\"CRUZ CAR TRADE SAS. Somos una empresa importadora y comercializadora de autopartes, repuestos, accesorios y ferreter\\u00eda automotriz para veh\\u00edculos livianos, de carga y transporte.\",\"url\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/\",\"name\":\"cruzcartrade.com\",\"description\":\"CRUZ CAR TRADE SAS. Somos una empresa importadora y comercializadora de autopartes, repuestos, accesorios y ferreter\\u00eda automotriz para veh\\u00edculos livianos, de carga y transporte.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/cruzcartrade.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Manijas Elevavidrios - cruzcartrade.com","description":"subcategoria manijas eleva vehiculos livianos","canonical_url":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/manijas-elevavidrios\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat\/84\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/cruzcartrade.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/shop\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/shop\/#listItem","position":2,"name":"Productos","item":"https:\/\/cruzcartrade.com\/en\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/#listItem","name":"Veh\u00edculos livianos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/#listItem","position":3,"name":"Veh\u00edculos livianos","item":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/manijas-elevavidrios\/#listItem","name":"Manijas Elevavidrios"},"previousItem":{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/shop\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/manijas-elevavidrios\/#listItem","position":4,"name":"Manijas Elevavidrios","previousItem":{"@type":"ListItem","@id":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/#listItem","name":"Veh\u00edculos livianos"}}]},{"@type":"CollectionPage","@id":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat\/84\/#collectionpage","url":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat\/84\/","name":"Manijas Elevavidrios - cruzcartrade.com","description":"subcategoria manijas eleva vehiculos livianos","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/cruzcartrade.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat\/84\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/cruzcartrade.com\/en\/#organization","name":"cruzcartrade.com","description":"CRUZ CAR TRADE SAS. Somos una empresa importadora y comercializadora de autopartes, repuestos, accesorios y ferreter\u00eda automotriz para veh\u00edculos livianos, de carga y transporte.","url":"https:\/\/cruzcartrade.com\/en\/"},{"@type":"WebSite","@id":"https:\/\/cruzcartrade.com\/en\/#website","url":"https:\/\/cruzcartrade.com\/en\/","name":"cruzcartrade.com","description":"CRUZ CAR TRADE SAS. Somos una empresa importadora y comercializadora de autopartes, repuestos, accesorios y ferreter\u00eda automotriz para veh\u00edculos livianos, de carga y transporte.","inLanguage":"en-US","publisher":{"@id":"https:\/\/cruzcartrade.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cruzcartrade.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cruzcartrade.com\/en\/shop\/\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/\" title=\"Veh\u00edculos livianos\">Veh\u00edculos livianos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tManijas Elevavidrios\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/cruzcartrade.com\/en"},{"label":"Productos","link":"https:\/\/cruzcartrade.com\/en\/shop\/"},{"label":"Veh\u00edculos livianos","link":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/"},{"label":"Manijas Elevavidrios","link":"https:\/\/cruzcartrade.com\/en\/product-category\/vehiculos-livianos\/manijas-elevavidrios\/"}],"_links":{"self":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat\/16"}],"wp:post_type":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product?product_cat=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}