{"id":13236,"date":"2026-04-02T20:43:52","date_gmt":"2026-04-03T01:43:52","guid":{"rendered":"https:\/\/cruzcartrade.com\/?post_type=product&#038;p=13236"},"modified":"2026-04-02T20:46:02","modified_gmt":"2026-04-03T01:46:02","slug":"chapa-capo-renault-r18-metalica","status":"publish","type":"product","link":"https:\/\/cruzcartrade.com\/en\/product\/chapa-capo-renault-r18-metalica\/","title":{"rendered":"Chapa Capo Renault R18 Metalica"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Chapa Capo Renault 18 Met\u00e1lica Zincada con Trompo. Material: Met\u00e1lica, Color: Zinc. Somos CRUZ CAR TRADE S.A.S. Comercializadora de autopartes y repuestos para veh\u00edculos livianos y pesados, Horario de atenci\u00f3n de lunes a s\u00e1bado de 8:00am a 5:00pm. (Las fotos de las publicaciones son de uso exclusivo y propiedad CRUZ CAR TRADE S.A.S.) Fontib\u00f3n, Bogot\u00e1 D.c. Ten presente que las im\u00e1genes del producto publicado son fotos de referencia y no corresponden necesariamente a la posici\u00f3n real.<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Chapa Capo Renault 18 Met\u00e1lica Zincada con Trompo. Material: Met\u00e1lica, Color: Zinc. Somos CRUZ CAR TRADE S.A.S. Comercializadora de autopartes y repuestos para veh\u00edculos livianos y pesados, Horario de atenci\u00f3n de lunes a s\u00e1bado de 8:00am a 5:00pm. (Las fotos de las publicaciones son de uso exclusivo y propiedad CRUZ CAR TRADE S.A.S.) Fontib\u00f3n, Bogot\u00e1 D.c. Ten presente que las im\u00e1genes del producto publicado son fotos de referencia y no corresponden necesariamente a la posici\u00f3n real.<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":13206,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[59],"product_cat":[101,16],"product_tag":[],"class_list":["post-13236","product","type-product","status-publish","has-post-thumbnail","product_brand-renault","product_cat-chapas-de-capo","product_cat-vehiculos-livianos","first","instock","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product\/13236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/comments?post=13236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/media\/13206"}],"wp:attachment":[{"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/media?parent=13236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_brand?post=13236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_cat?post=13236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cruzcartrade.com\/en\/wp-json\/wp\/v2\/product_tag?post=13236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}